{"id":19682,"date":"2025-08-25T12:06:39","date_gmt":"2025-08-25T16:06:39","guid":{"rendered":"http:\/\/laprovidenciaovalle.cl\/colegio\/?p=19682"},"modified":"2025-08-25T12:07:26","modified_gmt":"2025-08-25T16:07:26","slug":"%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89","status":"publish","type":"post","link":"http:\/\/laprovidenciaovalle.cl\/colegio\/%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89\/","title":{"rendered":"\ud83c\udf89 \u00a1Celebramos nuestro aniversario con m\u00e1s fuerza que nunca! \ud83c\udf89"},"content":{"rendered":"<p>Querida comunidad,<\/p>\n<p>Debido a las condiciones clim\u00e1ticas que nos acompa\u00f1aron recientemente, tuvimos que <strong>reprogramar las actividades de aniversario<\/strong>. Pero \u00a1las ganas de celebrar siguen intactas! \ud83c\udf27\ufe0f\u27a1\ufe0f\u2600\ufe0f<\/p>\n<p>Nos alegra anunciar que ya tenemos <strong>nueva fecha y programa actualizado<\/strong>, pensado para que todos puedan disfrutar de esta fiesta que nos une como colegio.<\/p>\n<p>Agradecemos la comprensi\u00f3n y el entusiasmo de cada familia, estudiante y funcionario. \u00a1Nos vemos para celebrar juntos con alegr\u00eda, identidad y comunidad!<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-19682 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/1-25\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/2-21\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/2-1-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/2-1-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/2-1-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/2-1-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/2-1-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/2-1.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/3-16\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/3-1-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/3-1-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/3-1-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/3-1-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/3-1-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/3-1.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/4-11\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/4-1-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/4-1-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/4-1-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/4-1-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/4-1-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/4-1.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/5-9\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/5-1-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/5-1-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/5-1-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/5-1-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/5-1-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/5-1.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/6-8\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/6-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/6-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/6-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/6-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/6-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/6.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/7-7\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/7-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/7-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/7-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/7-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/7-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/7.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/laprovidenciaovalle.cl\/colegio\/8-6\/'><img width=\"819\" height=\"1024\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/8-819x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/8-819x1024.png 819w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/8-240x300.png 240w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/8-768x960.png 768w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/8-120x150.png 120w, http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/8.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Querida comunidad, Debido a las condiciones clim\u00e1ticas que nos acompa\u00f1aron recientemente, tuvimos que reprogramar las actividades de aniversario. Pero \u00a1las ganas de celebrar siguen intactas! \ud83c\udf27\ufe0f\u27a1\ufe0f\u2600\ufe0f Nos alegra anunciar que ya tenemos nueva fecha y programa actualizado, pensado para que todos puedan disfrutar de esta fiesta que nos une como colegio. Agradecemos la comprensi\u00f3n y el entusiasmo de cada familia,&nbsp;<a href=\"http:\/\/laprovidenciaovalle.cl\/colegio\/%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89\/\">[&hellip;]<\/a><\/p>\n","protected":false},"author":5,"featured_media":19673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[40],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ud83c\udf89 \u00a1Celebramos nuestro aniversario con m\u00e1s fuerza que nunca! \ud83c\udf89 - Colegio La Providencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laprovidenciaovalle.cl\/colegio\/\ud83c\udf89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-\ud83c\udf89\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf89 \u00a1Celebramos nuestro aniversario con m\u00e1s fuerza que nunca! \ud83c\udf89 - Colegio La Providencia\" \/>\n<meta property=\"og:description\" content=\"Querida comunidad, Debido a las condiciones clim\u00e1ticas que nos acompa\u00f1aron recientemente, tuvimos que reprogramar las actividades de aniversario. Pero \u00a1las ganas de celebrar siguen intactas! \ud83c\udf27\ufe0f\u27a1\ufe0f\u2600\ufe0f Nos alegra anunciar que ya tenemos nueva fecha y programa actualizado, pensado para que todos puedan disfrutar de esta fiesta que nos une como colegio. Agradecemos la comprensi\u00f3n y el entusiasmo de cada familia,&nbsp;[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laprovidenciaovalle.cl\/colegio\/\ud83c\udf89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-\ud83c\udf89\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio La Providencia\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-25T16:06:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T16:07:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" value=\"Escrito por\">\n\t<meta name=\"twitter:data1\" value=\"Comunicaciones Colegio\">\n\t<meta name=\"twitter:label2\" value=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data2\" value=\"0 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#website\",\"url\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/\",\"name\":\"Colegio La Providencia\",\"description\":\"Ovalle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2025\/08\/1-1.png\",\"width\":1080,\"height\":1350},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89\/#webpage\",\"url\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89\/\",\"name\":\"\\ud83c\\udf89 \\u00a1Celebramos nuestro aniversario con m\\u00e1s fuerza que nunca! \\ud83c\\udf89 - Colegio La Providencia\",\"isPartOf\":{\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89\/#primaryimage\"},\"datePublished\":\"2025-08-25T16:06:39+00:00\",\"dateModified\":\"2025-08-25T16:07:26+00:00\",\"author\":{\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#\/schema\/person\/1035f45cd35e1948fb928fcdc74228fe\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/laprovidenciaovalle.cl\/colegio\/%f0%9f%8e%89-celebramos-nuestro-aniversario-con-mas-fuerza-que-nunca-%f0%9f%8e%89\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#\/schema\/person\/1035f45cd35e1948fb928fcdc74228fe\",\"name\":\"Comunicaciones Colegio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/5d0b6f6fbda2852def0dc3e63e38d319?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones Colegio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts\/19682"}],"collection":[{"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/comments?post=19682"}],"version-history":[{"count":2,"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts\/19682\/revisions"}],"predecessor-version":[{"id":19684,"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts\/19682\/revisions\/19684"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/media\/19673"}],"wp:attachment":[{"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/media?parent=19682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/categories?post=19682"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/tags?post=19682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}