{"id":13305,"date":"2024-04-01T11:06:55","date_gmt":"2024-04-01T14:06:55","guid":{"rendered":"http:\/\/laprovidenciaovalle.cl\/colegio\/?p=13305"},"modified":"2024-04-01T11:09:03","modified_gmt":"2024-04-01T14:09:03","slug":"amadrinamiento-especialidad-de-enfermeria","status":"publish","type":"post","link":"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/","title":{"rendered":"Amadrinamiento Especialidad de Enfermer\u00eda"},"content":{"rendered":"<p>Las estudiantes de cuarto medio de enfermer\u00eda amadrinaron a las estudiantes de tercero medio, en una acci\u00f3n plena de acogida y carisma providente, con la finalidad no s\u00f3lo de acompa\u00f1ar sino tambi\u00e9n de ayudar y orientar a sus compa\u00f1eras de especialidad m\u00e1s peque\u00f1as, fortaleciendo sus v\u00ednculos estudiantiles, la sana convivencia escolar, la motivaci\u00f3n escolar y los valores como la empat\u00eda, generosidad y amistad, tan importantes en nuestro mundo actual.<\/p>\n<p>La actividad comenz\u00f3 con unas palabras de bienvenida de las estudiantes, en su discurso la presidenta del cuarto medio &#8220;A&#8221;, P\u00eda Castillo se\u00f1al\u00f3 lo siguiente: &#8220;Como curso estamos muy felices y contentas con lo que hemos logrado, realizando este amadrinamiento, ya que es importante generar este vinculo con las estudiantes de tercero medio, somos buenos cursos y deseamos apoyarlas en todo el proceso que va ser este a\u00f1o para ellas, ya que se est\u00e1n integrando a esta especialidad y queremos que sientan que nosotras les estaremos apoyando siempre&#8221;. Por su parte Josefa Moroso, delegada de pastoral, mencion\u00f3 la importancia de contar con este acercamiento, ya que es primera vez que se realiza y que ellas no tuvieron la oportunidad, por lo que invit\u00f3 atesorar, cuidar y seguir con este rito los siguientes a\u00f1os.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-13306 size-large\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7656-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7656-1024x683.jpg 1024w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7656-300x200.jpg 300w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7656-768x512.jpg 768w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7656-1536x1024.jpg 1536w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7656-2048x1365.jpg 2048w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7656-150x100.jpg 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" class=\"alignnone wp-image-13307 size-large\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" srcset=\"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-683x1024.jpg 683w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-200x300.jpg 200w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-768x1152.jpg 768w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-1024x1536.jpg 1024w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-1365x2048.jpg 1365w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-100x150.jpg 100w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7673-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/> <img loading=\"lazy\" class=\"alignnone wp-image-13308 size-large\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7700-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7700-1024x683.jpg 1024w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7700-300x200.jpg 300w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7700-768x512.jpg 768w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7700-1536x1024.jpg 1536w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7700-2048x1365.jpg 2048w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7700-150x100.jpg 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" class=\"alignnone wp-image-13309 size-large\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-10.49.28-1-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-10.49.28-1-1024x768.jpeg 1024w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-10.49.28-1-300x225.jpeg 300w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-10.49.28-1-768x576.jpeg 768w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-10.49.28-1-150x112.jpeg 150w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-01-at-10.49.28-1.jpeg 1507w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" class=\"alignnone wp-image-13310 size-large\" src=\"http:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-3-1024x683.png\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-3-1024x683.png 1024w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-3-300x200.png 300w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-3-768x512.png 768w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-3-1536x1024.png 1536w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-3-2048x1365.png 2048w, https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/Diseno-sin-titulo-3-150x100.png 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las estudiantes de cuarto medio de enfermer\u00eda amadrinaron a las estudiantes de tercero medio, en una acci\u00f3n plena de acogida y carisma providente, con la finalidad no s\u00f3lo de acompa\u00f1ar sino tambi\u00e9n de ayudar y orientar a sus compa\u00f1eras de especialidad m\u00e1s peque\u00f1as, fortaleciendo sus v\u00ednculos estudiantiles, la sana convivencia escolar, la motivaci\u00f3n escolar y los valores como la empat\u00eda,&nbsp;<a href=\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/\">[&hellip;]<\/a><\/p>\n","protected":false},"author":5,"featured_media":13312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Amadrinamiento Especialidad de Enfermer\u00eda - Colegio La Providencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amadrinamiento Especialidad de Enfermer\u00eda - Colegio La Providencia\" \/>\n<meta property=\"og:description\" content=\"Las estudiantes de cuarto medio de enfermer\u00eda amadrinaron a las estudiantes de tercero medio, en una acci\u00f3n plena de acogida y carisma providente, con la finalidad no s\u00f3lo de acompa\u00f1ar sino tambi\u00e9n de ayudar y orientar a sus compa\u00f1eras de especialidad m\u00e1s peque\u00f1as, fortaleciendo sus v\u00ednculos estudiantiles, la sana convivencia escolar, la motivaci\u00f3n escolar y los valores como la empat\u00eda,&nbsp;[&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio La Providencia\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-01T14:06:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-01T14:09:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7702-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" value=\"Escrito por\">\n\t<meta name=\"twitter:data1\" value=\"Comunicaciones Colegio\">\n\t<meta name=\"twitter:label2\" value=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data2\" value=\"1 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#website\",\"url\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/\",\"name\":\"Colegio La Providencia\",\"description\":\"Ovalle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-content\/uploads\/2024\/04\/IMG_7702-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/#webpage\",\"url\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/\",\"name\":\"Amadrinamiento Especialidad de Enfermer\\u00eda - Colegio La Providencia\",\"isPartOf\":{\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/#primaryimage\"},\"datePublished\":\"2024-04-01T14:06:55+00:00\",\"dateModified\":\"2024-04-01T14:09:03+00:00\",\"author\":{\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#\/schema\/person\/1035f45cd35e1948fb928fcdc74228fe\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/laprovidenciaovalle.cl\/colegio\/amadrinamiento-especialidad-de-enfermeria\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#\/schema\/person\/1035f45cd35e1948fb928fcdc74228fe\",\"name\":\"Comunicaciones Colegio\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/laprovidenciaovalle.cl\/colegio\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5d0b6f6fbda2852def0dc3e63e38d319?s=96&d=mm&r=g\",\"caption\":\"Comunicaciones Colegio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts\/13305"}],"collection":[{"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/comments?post=13305"}],"version-history":[{"count":1,"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts\/13305\/revisions"}],"predecessor-version":[{"id":13311,"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/posts\/13305\/revisions\/13311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/media\/13312"}],"wp:attachment":[{"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/media?parent=13305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/categories?post=13305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laprovidenciaovalle.cl\/colegio\/wp-json\/wp\/v2\/tags?post=13305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}